{"id":126,"date":"2018-11-02T23:26:00","date_gmt":"2018-11-02T23:26:00","guid":{"rendered":"https:\/\/www.matoke.org\/?p=126"},"modified":"2021-01-23T19:18:45","modified_gmt":"2021-01-23T19:18:45","slug":"jahresbericht-2018","status":"publish","type":"post","link":"https:\/\/www.matoke.org\/index.php\/2018\/11\/02\/jahresbericht-2018\/","title":{"rendered":"Jahresbericht 2018"},"content":{"rendered":"\n<p>Liebe Spenderinnen, Spender und Unterst\u00fctzer vom Schulprojekt MATOKE e.V. in Uganda,<\/p>\n\n\n\n<p>sehr erfreulich war der Aufenthalt im Februar 2018, in der kurzen Zeit wurden mit einem gro\u00dfen, einheimischen Bautrupp, zwei praktische und wundersch\u00f6ne H\u00e4uschen f\u00fcr 40 Kindergartenkinder gebaut. Der Kindergarten war enorm wichtig, weil die Kinder, die fast alle nur Luganda sprechen, hier Englisch als Voraussetzung f\u00fcr den Schulbesuch lernen k\u00f6nnen.<\/p>\n\n\n\n<p>Die staatliche Registrierung der Schule ist abgeschlossen und alle 250 Kinder kommen sehr gerne zum Unterricht, der von 08.00 morgens bis nachmittags um 17.00 Uhr dauert. Neben vielen Reparaturen, ein Teil der Dachrinnen und Regentonnen waren kaputt, die \u00dcbernachtungsr\u00e4ume f\u00fcr M\u00e4dchen und Buben mussten renoviert werden, konnte endlich mit viel Aufwand und Verz\u00f6gerungen, auch die Stromanbindung der Schule fertig gestellt werden. Dazu war ein Transformator n\u00f6tig, der w\u00e4hrend des Aufbaus explodiert ist und bis der Neue beschafft war, dauerte es wieder Monate. Gott sei Dank kam niemand zu Schaden und der Transformator wurde kostenfrei ersetzt.<\/p>\n\n\n\n<p>Um unserem Anspruch, 100% der eingegangenen Spenden auch direkt f\u00fcr das Projekt verwenden zu k\u00f6nnen, war es notwendig geworden, im M\u00e4rz 2018 einen eigenen Verein, den MATOKE e.V. zu gr\u00fcnden, den Vorsitz hat Peter Gronau aus Nu\u00dfdorf \u00fcbernommen und Christa Gromotka, ebenfalls aus Nu\u00dfdorf, k\u00fcmmert sich als Projektleiterin weiter um den Erhalt und die Weiterentwicklung der Buschschule.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:43% auto\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/neu.einfach-gut-machen.de\/traunstein\/project\/schulprojekt-matoke-uganda-1\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" width=\"958\" height=\"636\" src=\"http:\/\/www.matoke.org\/wp-content\/uploads\/2018\/11\/shulprojekt-matoke-Uganda-sparkasse.jpg\" alt=\"\" class=\"wp-image-988 size-full\" srcset=\"https:\/\/www.matoke.org\/wp-content\/uploads\/2018\/11\/shulprojekt-matoke-Uganda-sparkasse.jpg 958w, https:\/\/www.matoke.org\/wp-content\/uploads\/2018\/11\/shulprojekt-matoke-Uganda-sparkasse-300x199.jpg 300w, https:\/\/www.matoke.org\/wp-content\/uploads\/2018\/11\/shulprojekt-matoke-Uganda-sparkasse-768x510.jpg 768w\" sizes=\"(max-width: 958px) 100vw, 958px\" \/><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p>Vom Finanzamt Traunstein ist die Gemeinn\u00fctzigkeit anerkannt.<\/p>\n\n\n\n<p><strong><em>2019 wollen wir die geplante Schulk\u00fcche und den erforderlichen Brunnen realisieren, deshalb d\u00fcrfen<\/em><\/strong> <strong><em>wir unser Projekt vom 05.11.2018 bis 03.01.2019 auf dem <strong><em>Spendenportasl<\/em><\/strong><\/em><\/strong> <strong><em>der Kreissparkasse Traunstein-Trostberg pr\u00e4sentieren. \u00dcber diesen Link erreichen sie das Portal:<\/em><\/strong> <a rel=\"noreferrer noopener\" href=\"https:\/\/neu.einfach-gut-machen.de\/traunstein\/project\/schulprojekt-matoke-uganda-1\" target=\"_blank\">https:\/\/neu.einfach-gut-machen.de\/traunstein\/project\/schulprojekt-matoke-uganda-1<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong><em>Hierbei haben wir die Chance, dass die Sparkasse die eingegangenen Spenden zus\u00e4tzlich aufstockt.<\/em><\/strong><\/p>\n\n\n\n<p>Wir w\u00fcrden uns sehr freuen, wenn Sie uns auch in diesem Jahr wieder mit einer Spende helfen k\u00f6nnten. Bitte verwenden Sie, wenn m\u00f6glich, das Spendenportal der Kreissparkasse Traunstein. <\/p>\n\n\n\n<p>F\u00fcr alle Betr\u00e4ge unter 200 \u20ac, die auf das Konto vom MATOKE e.V. eingehen, gilt der \u00dcberweisungsbeleg als Spendenquittung, Auf Wunsch, und f\u00fcr h\u00f6here Betr\u00e4ge stellen wir gerne eine Spendenquittung aus, dazu ben\u00f6tigen wir die Spenderadresse.<\/p>\n\n\n\n<p>Schulbildung ist ein Grundrecht f\u00fcr Kinder und ein Weg aus der Armut.<\/p>\n\n\n\n<p>Wir danken sehr herzlich f\u00fcr jede kleine und gro\u00dfe Unterst\u00fctzung.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Peter Gronau, Vorstand<\/p>\n\n\n\n<p>Christa Gromotka, Projektleitung<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/www.matoke.org\/wp-content\/uploads\/2021\/01\/Jahresbericht-2018-mit-Mitteilungs-an-Spender-wg.-Datenschutz.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Jahresbericht-2018-mit-Mitteilungs-an-Spender-wg.-Datenschutz<\/a><\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background\" href=\"https:\/\/www.matoke.org\/wp-content\/uploads\/2021\/01\/Jahresbericht-2018-mit-Mitteilungs-an-Spender-wg.-Datenschutz.pdf\" style=\"background-color:#ad2727\" target=\"_blank\" rel=\"noreferrer noopener\">Artikel Herunterladen &#8211; PDF<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Spenderinnen, Spender und Unterst\u00fctzer vom Schulprojekt MATOKE e.V. in Uganda, sehr erfreulich war der Aufenthalt im Februar 2018, in der kurzen Zeit wurden mit einem gro\u00dfen, einheimischen Bautrupp, zwei [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":988,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.matoke.org\/index.php\/wp-json\/wp\/v2\/posts\/126"}],"collection":[{"href":"https:\/\/www.matoke.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.matoke.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.matoke.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.matoke.org\/index.php\/wp-json\/wp\/v2\/comments?post=126"}],"version-history":[{"count":16,"href":"https:\/\/www.matoke.org\/index.php\/wp-json\/wp\/v2\/posts\/126\/revisions"}],"predecessor-version":[{"id":998,"href":"https:\/\/www.matoke.org\/index.php\/wp-json\/wp\/v2\/posts\/126\/revisions\/998"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.matoke.org\/index.php\/wp-json\/wp\/v2\/media\/988"}],"wp:attachment":[{"href":"https:\/\/www.matoke.org\/index.php\/wp-json\/wp\/v2\/media?parent=126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.matoke.org\/index.php\/wp-json\/wp\/v2\/categories?post=126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.matoke.org\/index.php\/wp-json\/wp\/v2\/tags?post=126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}